{"id":10620,"date":"2014-08-18T11:30:11","date_gmt":"2014-08-18T09:30:11","guid":{"rendered":"https:\/\/urbincasa.es\/blog\/wp-content\/uploads\/2014\/08\/atico-en-alicante-13.jpg"},"modified":"2014-08-18T11:30:11","modified_gmt":"2014-08-18T09:30:11","slug":"olympus-digital-camera-18-2","status":"inherit","type":"attachment","link":"https:\/\/urbincasa.es\/blog\/olympus-digital-camera-18-2\/","title":{"rendered":"\u00e1tico en alicante"},"author":3,"featured_media":0,"comment_status":"open","ping_status":"open","template":"","meta":[],"class_list":["post-10620","attachment","type-attachment","status-inherit","hentry"],"description":{"rendered":"<p class=\"attachment\"><a href='https:\/\/urbincasa.es\/blog\/wp-content\/uploads\/2014\/08\/atico-en-alicante-13.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"168\" src=\"https:\/\/urbincasa.es\/blog\/wp-content\/uploads\/2014\/08\/atico-en-alicante-13-300x168.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/urbincasa.es\/blog\/wp-content\/uploads\/2014\/08\/atico-en-alicante-13-300x168.jpg 300w, https:\/\/urbincasa.es\/blog\/wp-content\/uploads\/2014\/08\/atico-en-alicante-13-1024x576.jpg 1024w, https:\/\/urbincasa.es\/blog\/wp-content\/uploads\/2014\/08\/atico-en-alicante-13-500x281.jpg 500w, https:\/\/urbincasa.es\/blog\/wp-content\/uploads\/2014\/08\/atico-en-alicante-13-900x506.jpg 900w, https:\/\/urbincasa.es\/blog\/wp-content\/uploads\/2014\/08\/atico-en-alicante-13.jpg 1536w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n"},"caption":{"rendered":"<p>Dormitorio 3<\/p>\n"},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":1536,"height":864,"file":"2014\/08\/atico-en-alicante-13.jpg","sizes":{"thumbnail":{"file":"atico-en-alicante-13-150x150.jpg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/urbincasa.es\/blog\/wp-content\/uploads\/2014\/08\/atico-en-alicante-13-150x150.jpg"},"medium":{"file":"atico-en-alicante-13-300x168.jpg","width":300,"height":168,"mime_type":"image\/jpeg","source_url":"https:\/\/urbincasa.es\/blog\/wp-content\/uploads\/2014\/08\/atico-en-alicante-13-300x168.jpg"},"large":{"file":"atico-en-alicante-13-1024x576.jpg","width":1024,"height":576,"mime_type":"image\/jpeg","source_url":"https:\/\/urbincasa.es\/blog\/wp-content\/uploads\/2014\/08\/atico-en-alicante-13-1024x576.jpg"},"wptouch-new-thumbnail":{"file":"atico-en-alicante-13-300x300.jpg","width":300,"height":300,"mime_type":"image\/jpeg","source_url":"https:\/\/urbincasa.es\/blog\/wp-content\/uploads\/2014\/08\/atico-en-alicante-13-300x300.jpg"},"mini":{"file":"atico-en-alicante-13-230x195.jpg","width":230,"height":195,"mime_type":"image\/jpeg","source_url":"https:\/\/urbincasa.es\/blog\/wp-content\/uploads\/2014\/08\/atico-en-alicante-13-230x195.jpg"},"post-thumbnail":{"file":"atico-en-alicante-13-1000x288.jpg","width":1000,"height":288,"mime_type":"image\/jpeg","source_url":"https:\/\/urbincasa.es\/blog\/wp-content\/uploads\/2014\/08\/atico-en-alicante-13-1000x288.jpg"},"large-feature":{"file":"atico-en-alicante-13-1000x288.jpg","width":1000,"height":288,"mime_type":"image\/jpeg","source_url":"https:\/\/urbincasa.es\/blog\/wp-content\/uploads\/2014\/08\/atico-en-alicante-13-1000x288.jpg"},"small-feature":{"file":"atico-en-alicante-13-500x281.jpg","width":500,"height":281,"mime_type":"image\/jpeg","source_url":"https:\/\/urbincasa.es\/blog\/wp-content\/uploads\/2014\/08\/atico-en-alicante-13-500x281.jpg"},"foundation-featured-image":{"file":"atico-en-alicante-13-900x506.jpg","width":900,"height":506,"mime_type":"image\/jpeg","source_url":"https:\/\/urbincasa.es\/blog\/wp-content\/uploads\/2014\/08\/atico-en-alicante-13-900x506.jpg"},"full":{"file":"atico-en-alicante-13.jpg","width":1536,"height":864,"mime_type":"image\/jpeg","source_url":"https:\/\/urbincasa.es\/blog\/wp-content\/uploads\/2014\/08\/atico-en-alicante-13.jpg"}},"image_meta":{"aperture":3.5,"credit":"","camera":"E-PL6","caption":"","created_timestamp":1408014151,"copyright":"","focal_length":"14","iso":"200","shutter_speed":"0.0166666666667","title":"OLYMPUS DIGITAL CAMERA"}},"post":null,"source_url":"https:\/\/urbincasa.es\/blog\/wp-content\/uploads\/2014\/08\/atico-en-alicante-13.jpg","filename":"atico-en-alicante-13.jpg","filesize":241182,"_links":{"self":[{"href":"https:\/\/urbincasa.es\/blog\/wp-json\/wp\/v2\/media\/10620","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/urbincasa.es\/blog\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/urbincasa.es\/blog\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/urbincasa.es\/blog\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/urbincasa.es\/blog\/wp-json\/wp\/v2\/comments?post=10620"}]}}