{"id":8619,"date":"2020-05-15T18:08:15","date_gmt":"2020-05-15T16:08:15","guid":{"rendered":"https:\/\/urbincasa.es\/blog\/?p=8619"},"modified":"2020-05-17T12:08:05","modified_gmt":"2020-05-17T10:08:05","slug":"la-vivienda-un-refugio-de-inversion-seguro","status":"publish","type":"post","link":"https:\/\/urbincasa.es\/blog\/2020\/05\/la-vivienda-un-refugio-de-inversion-seguro\/","title":{"rendered":"La vivienda, un refugio de inversi\u00f3n seguro"},"content":{"rendered":"<div id=\"bsf_rt_marker\"><\/div><p>Las promociones de Urbincasa en la Costa C\u00e1lida, Alicante y Benidorm ofrecen la oportunidad de invertir, disfrutar plenamente de un hogar y hacerlo con la tranquilidad que aporta la seguridad sanitaria.<\/p>\n<p>Vamos m\u00e1s all\u00e1 de un lugar donde disfrutar de las vacaciones, te ofrecemos hogares en los que vivir todo el a\u00f1o en unas condiciones fant\u00e1sticas, con un clima envidiable y en el marco de un ambiente de relax.<\/p>\n<p>Hoy por hoy, la Regi\u00f3n de Murcia es la que menos casos de contagio y menos fallecidos por coronavirus de toda Espa\u00f1a lo que la sit\u00faa como un espacio seguro frente a la crisis sanitaria.<\/p>\n<p>Comprar una vivienda siempre ha sido una inversi\u00f3n, en unas \u00e9pocas m\u00e1s rentable que en otras, pero sin perder atractivo como sector en el que colocar los ahorros. Son muchos los factores que pueden aumentar el beneficio econ\u00f3mico de adquirir una vivienda nueva, y en estos tiempos de inseguridad sanitaria, se perfila como uno de los m\u00e1s importantes el lugar escogido.<\/p>\n<p>La Regi\u00f3n de Murcia ha sido la comunidad aut\u00f3noma de Espa\u00f1a que menos ha acusado el descenso de la compraventa de viviendas durante el mes de marzo, cuando se decreta el estado de alarma, y el pa\u00eds pr\u00e1cticamente se paraliza. Frente a una bajada nacional del 18,6% en Murcia se ha situado en el 4,2%.<\/p>\n<p>Si hay algo que caracteriza a las urbanizaciones en marcha es la combinaci\u00f3n de la alta calidad de las viviendas con la amplitud, espaciosidad y gran dotaci\u00f3n de las zonas comunes. Es tan importante el espacio que solos disfrutamos nuestros en el interior de la vivienda como los servicios de los que disponemos en el entorno m\u00e1s inmediato. M\u00e1s a\u00fan en estos momentos donde en los que poco a poco se restablece la normalidad.<\/p>\n<figure id=\"attachment_8622\" aria-describedby=\"caption-attachment-8622\" style=\"width: 800px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-8622\" src=\"https:\/\/urbincasa.es\/blog\/wp-content\/uploads\/2020\/05\/Copia-de-Edificio-Los-Flamencos-DIC08-1-1024x614.jpg\" alt=\"\" width=\"800\" height=\"480\" \/><figcaption id=\"caption-attachment-8622\" class=\"wp-caption-text\">Apartamentos de lujo en la Costa C\u00e1lida<\/figcaption><\/figure>\n<p>Sin duda, ese entorno m\u00e1s pr\u00f3ximo y cercano es un plus de revalorizaci\u00f3n de las viviendas, un elemento distintivo que mejora su rentabilidad econ\u00f3mica, y por supuesto, de disfrute personal y familiar.<\/p>\n<p>Amplios jardines para pasear, grandes piscinas, zona de juegos para ni\u00f1os, gimnasio, un \u00e1rea para mascotas y todo ello teniendo siempre al alcance de la vista el mar. Ese inmenso regalo de la naturaleza que tanta calma y tranquilidad nos aporta.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Las promociones de Urbincasa en la Costa C\u00e1lida, Alicante y Benidorm ofrecen la oportunidad de invertir, disfrutar plenamente de un hogar y hacerlo con la tranquilidad que aporta la seguridad sanitaria. Vamos m\u00e1s all\u00e1 de un lugar donde disfrutar de las vacaciones, te ofrecemos hogares en los que vivir todo el a\u00f1o en unas condiciones [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":8442,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[801,813,802,798,823,800,867,836],"tags":[],"class_list":["post-8619","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-benidorm","category-calidad","category-costa-blanca","category-costa-calida","category-hogares-felices","category-mar-mediterraneo","category-vivienda-nueva","category-vivir-en-espana"],"_links":{"self":[{"href":"https:\/\/urbincasa.es\/blog\/wp-json\/wp\/v2\/posts\/8619","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/urbincasa.es\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/urbincasa.es\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/urbincasa.es\/blog\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/urbincasa.es\/blog\/wp-json\/wp\/v2\/comments?post=8619"}],"version-history":[{"count":3,"href":"https:\/\/urbincasa.es\/blog\/wp-json\/wp\/v2\/posts\/8619\/revisions"}],"predecessor-version":[{"id":8623,"href":"https:\/\/urbincasa.es\/blog\/wp-json\/wp\/v2\/posts\/8619\/revisions\/8623"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/urbincasa.es\/blog\/wp-json\/wp\/v2\/media\/8442"}],"wp:attachment":[{"href":"https:\/\/urbincasa.es\/blog\/wp-json\/wp\/v2\/media?parent=8619"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/urbincasa.es\/blog\/wp-json\/wp\/v2\/categories?post=8619"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/urbincasa.es\/blog\/wp-json\/wp\/v2\/tags?post=8619"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}